{"id":3701,"count":1,"description":"","link":"https:\/\/spmodels.net\/runway\/tag\/best-and-creative-professional-fashion-stylist-dresser-service-for-hire-in-kuala-terengganu\/","name":"Best and Creative Professional Fashion Stylist &amp; Dresser Service For Hire in Kuala Terengganu","slug":"best-and-creative-professional-fashion-stylist-dresser-service-for-hire-in-kuala-terengganu","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/spmodels.net\/runway\/wp-json\/wp\/v2\/tags\/3701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spmodels.net\/runway\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/spmodels.net\/runway\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/spmodels.net\/runway\/wp-json\/wp\/v2\/posts?tags=3701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}